{"id":6834,"date":"2024-08-29T21:51:20","date_gmt":"2024-08-29T19:51:20","guid":{"rendered":"https:\/\/rehwald-associates.com\/?page_id=6834"},"modified":"2025-09-30T10:21:50","modified_gmt":"2025-09-30T08:21:50","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/rehwald-associates.com\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Datenschutz\u00aderkl\u00e4rung<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">1. Datenschutz auf einen Blick<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Datenerfassung auf dieser Website<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie erfassen wir Ihre Daten?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.&nbsp;B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.&nbsp;B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Analyse-Tools und Tools von Dritt\u00adanbietern<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit sogenannten Analyseprogrammen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Hosting<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir hosten die Inhalte unserer Website bei folgendem Anbieter:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">IONOS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Anbieter ist die IONOS SE, Elgendorfer Str. 57, 56410 Montabaur (nachfolgend IONOS). Wenn Sie unsere Website besuchen, erfasst IONOS verschiedene Logfiles inklusive Ihrer IP-Adressen. Details entnehmen Sie der Datenschutzerkl\u00e4rung von IONOS: <a href=\"https:\/\/www.ionos.de\/terms-gtc\/terms-privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.ionos.de\/terms-gtc\/terms-privacy<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verwendung von IONOS erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an einer m\u00f6glichst zuverl\u00e4ssigen Darstellung unserer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Auftragsverarbeitung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Allgemeine Hinweise und Pflicht\u00adinformationen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Datenschutz<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur verantwortlichen Stelle<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rehwald Associates GmbH<br>Gesch\u00e4ftsf\u00fchrer: Manuel Rehwald<br>Altk\u00f6nigstr. 4a<br>D-61462 K\u00f6nigstein im Taunus<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Telefon: +49 6174 9357 639<br>E-Mail: datenschutz@rehwald-associates.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.&nbsp;B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z.&nbsp;B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verarbeitung personenbezogener Daten erfolgt auf Grundlage der Datenschutz-Grundverordnung (DSGVO) sowie \u2013 soweit anwendbar \u2013 der schweizerischen Datenschutzgesetzgebung (revDSG).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rechtsgrundlagen sind insbesondere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Einwilligung der betroffenen Person<\/strong> (Art. 6 Abs. 1 lit. a DSGVO \/ Art. 31 Abs. 1 DSG revDSG)<\/li>\n\n\n\n<li><strong>Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen<\/strong> (Art. 6 Abs. 1 lit. b DSGVO \/ Art. 31 Abs. 2 lit. a DSG revDSG)<\/li>\n\n\n\n<li><strong>Erf\u00fcllung rechtlicher Verpflichtungen<\/strong> (Art. 6 Abs. 1 lit. c DSGVO \/ Art. 31 Abs. 1 DSG revDSG)<\/li>\n\n\n\n<li><strong>Wahrung berechtigter Interessen der verantwortlichen Stelle oder Dritter<\/strong> (Art. 6 Abs. 1 lit. f DSGVO \/ Art. 31 Abs. 2 lit. b DSG revDSG)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur Datenweitergabe in datenschutzrechtlich nicht sichere Drittstaaten sowie die Weitergabe an US-Unternehmen, die nicht DPF-zertifiziert sind<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wir verwenden unter anderem Tools von Unternehmen mit Sitz in datenschutzrechtlich nicht sicheren Drittstaaten sowie US-Tools, deren Anbieter nicht nach dem EU-US-Data Privacy Framework (DPF) zertifiziert sind. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Staaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in datenschutzrechtlich unsicheren Drittstaaten kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir weisen darauf hin, dass die USA als sicherer Drittstaat grunds\u00e4tzlich ein mit der EU vergleichbares Datenschutzniveau aufweisen. Eine Daten\u00fcbertragung in die USA ist danach zul\u00e4ssig, wenn der Empf\u00e4nger eine Zertifizierung unter dem \u201eEU-US Data Privacy Framework\u201c (DPF) besitzt oder \u00fcber geeignete zus\u00e4tzliche Garantien verf\u00fcgt. Informationen zu \u00dcbermittlungen an Drittstaaten einschlie\u00dflich der Datenempf\u00e4nger finden Sie in dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empf\u00e4nger von personenbezogenen Daten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im Rahmen unserer Gesch\u00e4ftst\u00e4tigkeit arbeiten wir mit verschiedenen externen Stellen zusammen. Dabei ist teilweise auch eine \u00dcbermittlung von personenbezogenen Daten an diese externen Stellen erforderlich. Wir geben personenbezogene Daten nur dann an externe Stellen weiter, wenn dies im Rahmen einer Vertragserf\u00fcllung erforderlich ist, wenn wir gesetzlich hierzu verpflichtet sind (z.&nbsp;B. Weitergabe von Daten an Steuerbeh\u00f6rden), wenn wir ein berechtigtes Interesse nach Art. 6 Abs. 1 lit. f DSGVO an der Weitergabe haben oder wenn eine sonstige Rechtsgrundlage die Datenweitergabe erlaubt. Beim Einsatz von Auftragsverarbeitern geben wir personenbezogene Daten unserer Kunden nur auf Grundlage eines g\u00fcltigen Vertrags \u00fcber Auftragsverarbeitung weiter. Im Falle einer gemeinsamen Verarbeitung wird ein Vertrag \u00fcber gemeinsame Verarbeitung geschlossen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auskunft, Berichtigung und L\u00f6schung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n\n\n\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Datenerfassung auf dieser Website<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Cookies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Datenpakete und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookies k\u00f6nnen von uns (First-Party-Cookies) oder von Drittunternehmen stammen (sog. Third-Party-Cookies). Third-Party-Cookies erm\u00f6glichen die Einbindung bestimmter Dienstleistungen von Drittunternehmen innerhalb von Webseiten (z.&nbsp;B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w\u00fcrden (z.&nbsp;B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies k\u00f6nnen zur Auswertung des Nutzerverhaltens oder zu Werbezwecken verwendet werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.&nbsp;B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z.&nbsp;B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG); die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Welche Cookies und Dienste auf dieser Website eingesetzt werden, k\u00f6nnen Sie dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kontaktformular<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anfrage per E-Mail, Telefon oder Telefax<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5. Soziale Medien<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Facebook<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dieser Website sind Elemente des sozialen Netzwerks Facebook integriert. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, Merrion Road, Dublin 4, D04 X2K5, Irland. Die erfassten Daten werden nach Aussage von Facebook jedoch auch in die USA und in andere Drittl\u00e4nder \u00fcbertragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine \u00dcbersicht \u00fcber die Facebook Social-Media-Elemente finden Sie hier: <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Social-Media-Element aktiv ist, wird eine direkte Verbindung zwischen Ihrem Endger\u00e4t und dem Facebook-Server hergestellt. Facebook erh\u00e4lt dadurch die Information, dass Sie mit Ihrer IP-Adresse diese Website besucht haben. Wenn Sie den Facebook \u201eLike-Button\u201c anklicken, w\u00e4hrend Sie in Ihrem Facebook-Account eingeloggt sind, k\u00f6nnen Sie die Inhalte dieser Website auf Ihrem Facebook-Profil verlinken. Dadurch kann Facebook den Besuch dieser Website Ihrem Benutzerkonto zuordnen. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Facebook erhalten. Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Facebook unter: <a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/de-de.facebook.com\/privacy\/explanation<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soweit mit Hilfe des hier beschriebenen Tools personenbezogene Daten auf unserer Website erfasst und an Facebook weitergeleitet werden, sind wir und die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland gemeinsam f\u00fcr diese Datenverarbeitung verantwortlich (Art. 26 DSGVO). Die gemeinsame Verantwortlichkeit beschr\u00e4nkt sich dabei ausschlie\u00dflich auf die Erfassung der Daten und deren Weitergabe an Facebook. Die nach der Weiterleitung erfolgende Verarbeitung durch Facebook ist nicht Teil der gemeinsamen Verantwortung. Die uns gemeinsam obliegenden Verpflichtungen wurden in einer Vereinbarung \u00fcber gemeinsame Verarbeitung festgehalten. Den Wortlaut der Vereinbarung finden Sie unter: <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. Laut dieser Vereinbarung sind wir f\u00fcr die Erteilung der Datenschutzinformationen beim Einsatz des Facebook-Tools und f\u00fcr die datenschutzrechtlich sichere Implementierung des Tools auf unserer Website verantwortlich. F\u00fcr die Datensicherheit der Facebook-Produkte ist Facebook verantwortlich. Betroffenenrechte (z.&nbsp;B. Auskunftsersuchen) hinsichtlich der bei Facebook verarbeiteten Daten k\u00f6nnen Sie direkt bei Facebook geltend machen. Wenn Sie die Betroffenenrechte bei uns geltend machen, sind wir verpflichtet, diese an Facebook weiterzuleiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> und <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/s\/participant-search\/participant-detail?contact=true&amp;id=a2zt0000000GnywAAC&amp;status=Active\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/s\/participant-search\/participant-detail?contact=true&amp;id=a2zt0000000GnywAAC&amp;status=Active<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">X (ehemals Twitter)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dieser Website sind Funktionen des Dienstes X (ehemals Twitter) eingebunden. Diese Funktionen werden angeboten durch den Mutterkonzern X Corp., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA. F\u00fcr die Datenverarbeitung von au\u00dferhalb der USA lebenden Personen ist die Niederlassung Twitter International Unlimited Company, One Cumberland Place, Fenian Street, Dublin 2, D02 AX07, Irland, verantwortlich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Social-Media-Element aktiv ist, wird eine direkte Verbindung zwischen Ihrem Endger\u00e4t und dem X-Server hergestellt. X (ehemals Twitter) erh\u00e4lt dadurch Informationen \u00fcber den Besuch dieser Website durch Sie. Durch das Benutzen von X (ehemals Twitter) und der Funktion \u201eRe-Tweet\u201c bzw. \u201eRepost\u201c werden die von Ihnen besuchten Websites mit Ihrem X (ehemals Twitter)-Account verkn\u00fcpft und anderen Nutzern bekannt gegeben. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch X (ehemals Twitter) erhalten. Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von X (ehemals Twitter) unter: <a href=\"https:\/\/x.com\/de\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/x.com\/de\/privacy<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/gdpr.x.com\/en\/controller-to-controller-transfers.html<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihre Datenschutzeinstellungen bei X (ehemals Twitter) k\u00f6nnen Sie in den Konto-Einstellungen unter <a href=\"https:\/\/x.com\/settings\/account\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/x.com\/settings\/account<\/a> \u00e4ndern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Linkedin<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dieser Website sind Funktionen des Dienstes Linkedin eingebunden. Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Social-Media-Element aktiv ist, wird eine direkte Verbindung zwischen Ihrem Endger\u00e4t und dem Linkedin-Server hergestellt. Linkedin erh\u00e4lt dadurch die Information, dass Sie mit Ihrer IP-Adresse diese Website besucht haben. Wenn Sie den Linkedin \u201eShare-Button\u201c anklicken, w\u00e4hrend Sie in Ihrem Linkedin-Account eingeloggt sind, k\u00f6nnen Sie die Inhalte dieser Website auf Ihrem Linkedin-Profil verlinken. Dadurch kann Linkedin den Besuch dieser Website Ihrem Benutzerkonto zuordnen. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Linkedin erhalten. Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Facebook unter: <a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/de.linkedin.com\/legal\/privacy-policy?<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6. Analyse-Tools und Werbung<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">WP Statistics<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Website nutzt das Analysetool WP Statistics, um Besucherzugriffe statistisch auszuwerten. Anbieter ist Veronalabs, Tatari 64, 10134, Tallinn, Estland (<a href=\"https:\/\/veronalabs.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/veronalabs.com<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit WP Statistics k\u00f6nnen wir die Nutzung unserer Website analysieren. WP Statistics erfasst dabei u.&nbsp;a. Logdateien (IP-Adresse, Referrer, verwendete Browser, Herkunft des Nutzers, verwendete Suchmaschine) und Aktionen, die die Websitebesucher auf der Seite get\u00e4tigt haben (z.&nbsp;B. Klicks und Ansichten).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die mit WP Statistics erfassten Daten werden ausschlie\u00dflich auf unserem eigenen Server gespeichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nutzung dieses Analyse-Tools erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an der anonymisierten Analyse des Nutzerverhaltens, um sowohl unser Webangebot als auch unsere Werbung zu optimieren. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">IP-Anonymisierung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir verwenden WP Statistics mit anonymisierter IP. Ihre IP-Adresse wird dabei gek\u00fcrzt, sodass diese Ihnen nicht mehr direkt zugeordnet werden kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7. Newsletter<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Newsletter\u00addaten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie den auf der Website angebotenen Newsletter beziehen m\u00f6chten, ben\u00f6tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die \u00dcberpr\u00fcfung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht bzw. nur auf freiwilliger Basis erhoben. Diese Daten verwenden wir ausschlie\u00dflich f\u00fcr den Versand der angeforderten Informationen und geben diese nicht an Dritte weiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verarbeitung der in das Newsletteranmeldeformular eingegebenen Daten erfolgt ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k\u00f6nnen Sie jederzeit widerrufen, etwa \u00fcber den \u201eAustragen\u201c-Link im Newsletter. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die von Ihnen zum Zwecke des Newsletter-Bezugs bei uns hinterlegten Daten werden von uns bis zu Ihrer Austragung aus dem Newsletter bei uns bzw. dem Newsletterdiensteanbieter gespeichert und nach der Abbestellung des Newsletters oder nach Zweckfortfall aus der Newsletterverteilerliste gel\u00f6scht. Wir behalten uns vor, E-Mail-Adressen aus unserem Newsletterverteiler nach eigenem Ermessen im Rahmen unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO zu l\u00f6schen oder zu sperren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daten, die zu anderen Zwecken bei uns gespeichert wurden, bleiben hiervon unber\u00fchrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Ihrer Austragung aus der Newsletterverteilerliste wird Ihre E-Mail-Adresse bei uns bzw. dem Newsletterdiensteanbieter ggf. in einer Blacklist gespeichert, sofern dies zur Verhinderung k\u00fcnftiger Mailings erforderlich ist. Die Daten aus der Blacklist werden nur f\u00fcr diesen Zweck verwendet und nicht mit anderen Daten zusammengef\u00fchrt. Dies dient sowohl Ihrem Interesse als auch unserem Interesse an der Einhaltung der gesetzlichen Vorgaben beim Versand von Newslettern (berechtigtes Interesse im Sinne des Art. 6 Abs. 1 lit. f DSGVO). Die Speicherung in der Blacklist ist zeitlich nicht befristet. <strong>Sie k\u00f6nnen der Speicherung widersprechen, sofern Ihre Interessen unser berechtigtes Interesse \u00fcberwiegen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8. Plugins und Tools<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Font Awesome<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten und Symbolen Font Awesome. Anbieter ist die Fonticons, Inc., 6 Porter Road Apartment 3R, Cambridge, Massachusetts, USA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Fonts in ihren Browsercache, um Texte, Schriftarten und Symbole korrekt anzuzeigen. Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Font Awesome aufnehmen. Hierdurch erlangt Font Awesome Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse diese Website aufgerufen wurde. Die Nutzung von Font Awesome erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an der einheitlichen Darstellung des Schriftbildes auf unserer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Ihr Browser Font Awesome nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem Computer genutzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen zu Font Awesome finden Sie&nbsp;und in der Datenschutzerkl\u00e4rung von Font Awesome unter: <a href=\"https:\/\/fontawesome.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/fontawesome.com\/privacy<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Maps<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Seite nutzt den Kartendienst Google Maps. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland. Mit Hilfe dieses Dienstes k\u00f6nnen wir Kartenmaterial auf unserer Website einbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP-Adresse zu speichern. Diese Informationen werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Der Anbieter dieser Seite hat keinen Einfluss auf diese Daten\u00fcbertragung. Wenn Google Maps aktiviert ist, kann Google zum Zwecke der einheitlichen Darstellung der Schriftarten Google Fonts verwenden. Beim Aufruf von Google Maps l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit der von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> und <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Unternehmen verf\u00fcgt \u00fcber eine Zertifizierung nach dem \u201eEU-US Data Privacy Framework\u201c (DPF). Der DPF ist ein \u00dcbereinkommen zwischen der Europ\u00e4ischen Union und den USA, der die Einhaltung europ\u00e4ischer Datenschutzstandards bei Datenverarbeitungen in den USA gew\u00e4hrleisten soll. Jedes nach dem DPF zertifizierte Unternehmen verpflichtet sich, diese Datenschutzstandards einzuhalten. Weitere Informationen hierzu erhalten Sie vom Anbieter unter folgendem Link: <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutz\u00aderkl\u00e4rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6834","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/pages\/6834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/comments?post=6834"}],"version-history":[{"count":3,"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/pages\/6834\/revisions"}],"predecessor-version":[{"id":7125,"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/pages\/6834\/revisions\/7125"}],"wp:attachment":[{"href":"https:\/\/rehwald-associates.com\/de\/wp-json\/wp\/v2\/media?parent=6834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}